{"id":13767,"date":"2022-01-07T14:43:19","date_gmt":"2022-01-07T19:43:19","guid":{"rendered":"http:\/\/149.4.100.129\/hsi-stem\/?page_id=13767"},"modified":"2022-01-07T14:47:51","modified_gmt":"2022-01-07T19:47:51","slug":"hsmrf-contact-us","status":"publish","type":"page","link":"https:\/\/www.qc.cuny.edu\/hsi-stem\/hsmrf-contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"\n[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.4.5&#8243; custom_padding=&#8221;||54px|||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][dsm_text_divider header=&#8221;Contact Us&#8221; text_alignment=&#8221;left&#8221; color=&#8221;#E71939&#8243; divider_weight=&#8221;2px&#8221; _builder_version=&#8221;4.14.5&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Open Sans|600|||||||&#8221; header_text_color=&#8221;#000000&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;][\/dsm_text_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.14.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.14.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.14.5&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Open Sans||||||||&#8221; text_font_size=&#8221;16px&#8221; header_4_font=&#8221;Open Sans|600|||on||||&#8221; header_4_text_color=&#8221;#000000&#8243; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<h4>Queens College Mathematics Redesign Team<\/h4>\n<ul>\n<li><strong>Anisha Clarke<\/strong> \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Email: <a href=\"mailto:aclarke@qc.cuny.edu\">aclarke@qc.cuny.edu<\/a><\/li>\n<li><strong>Joe Pastore<\/strong> \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Email: <a href=\"mailto:jpastore@qc.cuny.edu\">jpastore@qc.cuny.edu<\/a><\/li>\n<li><strong>Michael Joseph \u00a0\u00a0 \u00a0\u00a0<\/strong> Email: <a href=\"mailto:michael.joseph@qc.cuny.edu\">michael.joseph@qc.cuny.edu<\/a><\/li>\n<\/ul>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.14.5&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Open Sans||||||||&#8221; text_font_size=&#8221;16px&#8221; header_4_font=&#8221;Open Sans|600|||on||||&#8221; header_4_text_color=&#8221;#000000&#8243; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<h4>HSI-STEM Team<\/h4>\n<ul>\n<li><strong>Sabrina Avila, Director of Course Redesign<\/strong> \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Email: <a href=\"mailto:sabrina.avila@qc.cuny.edu\">sabrina.avila@qc.cuny.edu<\/a><\/li>\n<li><strong>Jennifer Valad, Director of Peer Mentoring<\/strong> \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Email: <a href=\"mailto:jennifer.valad@qc.cuny.edu\">jennifer.valad@qc.cuny.edu<\/a><\/li>\n<li><strong>Corinna Singleman, Peer Mentoring Advisor<\/strong> \u00a0\u00a0\u00a0\u00a0 Email: <a href=\"mailto:corinna.singleman@qc.cuny.edu\">corinna.singleman@qc.cuny.edu<\/a><\/li>\n<li><strong>Patrick Johnson, Senior Research Scholar<\/strong> \u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 Email: <a href=\"mailto:patrick.johnson@qc.cuny.edu\">patrick.johnson@qc.cuny.edu<\/a><\/li>\n<li><strong>Eva Fernandez, Assistant Provost and PI<\/strong> \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Email: <a href=\"mailto:efernandez@qc.cuny.edu\">efernandez@qc.cuny.edu<\/a><\/li>\n<\/ul>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p><div class=\"et_pb_module dsm_text_divider dsm_text_divider_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dsm-text-divider-wrapper dsm-text-divider-align-left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"dsm-text-divider-before dsm-divider\"><\/div>\n\t\t\t\t<h3 class=\"dsm-text-divider-header et_pb_module_header\"><span>Contact Us<\/span><\/h3>\n\t\t\t\t<div class=\"dsm-text-divider-after dsm-divider\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>Queens College Mathematics Redesign Team Anisha Clarke \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Email: aclarke@qc.cuny.edu Joe Pastore \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Email: jpastore@qc.cuny.edu Michael Joseph \u00a0\u00a0 \u00a0\u00a0 Email: michael.joseph@qc.cuny.edu HSI-STEM Team Sabrina Avila, Director of Course Redesign \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Email: sabrina.avila@qc.cuny.edu Jennifer Valad, Director of Peer Mentoring \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Email: [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"wf_page_folders":[402],"class_list":["post-13767","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.qc.cuny.edu\/hsi-stem\/wp-json\/wp\/v2\/pages\/13767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.qc.cuny.edu\/hsi-stem\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.qc.cuny.edu\/hsi-stem\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.qc.cuny.edu\/hsi-stem\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.qc.cuny.edu\/hsi-stem\/wp-json\/wp\/v2\/comments?post=13767"}],"version-history":[{"count":0,"href":"https:\/\/www.qc.cuny.edu\/hsi-stem\/wp-json\/wp\/v2\/pages\/13767\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.qc.cuny.edu\/hsi-stem\/wp-json\/wp\/v2\/media?parent=13767"}],"wp:term":[{"taxonomy":"wf_page_folders","embeddable":true,"href":"https:\/\/www.qc.cuny.edu\/hsi-stem\/wp-json\/wp\/v2\/wf_page_folders?post=13767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}